{"id":124112,"date":"2025-11-28T04:30:10","date_gmt":"2025-11-28T07:30:10","guid":{"rendered":"https:\/\/rem.sema.mt.gov.br\/areas-de-atuacao-map\/valorizando-as-cadeias-da-sociobiodiversidade-do-xingu-pequi-um-sonho-possivel-15\/"},"modified":"2025-11-28T04:30:10","modified_gmt":"2025-11-28T07:30:10","slug":"valorizando-as-cadeias-da-sociobiodiversidade-do-xingu-pequi-um-sonho-possivel-15","status":"publish","type":"areas-de-atuacao-map","link":"https:\/\/rem.sema.mt.gov.br\/en\/areas-de-atuacao-map\/valorizando-as-cadeias-da-sociobiodiversidade-do-xingu-pequi-um-sonho-possivel-15\/","title":{"rendered":"Valorizando as Cadeias da Sociobiodiversidade do Xingu \u2013 \u201cPequi um Sonho Poss\u00edvel\u201d"},"parent":0,"template":"","meta":{"_eb_attr":"","ocean_front_end_style_editor":"no","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","projetos":"Valorizando as Cadeias da Sociobiodiversidade do Xingu \u2013 \u201cPequi um Sonho Poss\u00edvel\u201d","subprograma":"Agricultura Familiar e de Povos e Comunidades Tradicionais","localizacao":"-13.11575,-52.3035","cor_do_marcador":"#f79633"},"categoria-de-projetos-subprogram":[46],"class_list":["post-124112","areas-de-atuacao-map","type-areas-de-atuacao-map","status-publish","hentry","categoria-de-projetos-subprogram-agricultura-familiar-e-de-povos-e-comunidades-tradicionais","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Valorizando as Cadeias da Sociobiodiversidade do Xingu \u2013 \u201cPequi um Sonho Poss\u00edvel\u201d - REM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rem.sema.mt.gov.br\/en\/areas-de-atuacao-map\/valorizando-as-cadeias-da-sociobiodiversidade-do-xingu-pequi-um-sonho-possivel-15\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valorizando as Cadeias da Sociobiodiversidade do Xingu \u2013 \u201cPequi um Sonho Poss\u00edvel\u201d - REM\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rem.sema.mt.gov.br\/en\/areas-de-atuacao-map\/valorizando-as-cadeias-da-sociobiodiversidade-do-xingu-pequi-um-sonho-possivel-15\/\" \/>\n<meta property=\"og:site_name\" content=\"REM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/areas-de-atuacao-map\\\/valorizando-as-cadeias-da-sociobiodiversidade-do-xingu-pequi-um-sonho-possivel-15\\\/\",\"url\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/areas-de-atuacao-map\\\/valorizando-as-cadeias-da-sociobiodiversidade-do-xingu-pequi-um-sonho-possivel-15\\\/\",\"name\":\"Valorizando as Cadeias da Sociobiodiversidade do Xingu \u2013 \u201cPequi um Sonho Poss\u00edvel\u201d - REM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/#website\"},\"datePublished\":\"2025-11-28T07:30:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/areas-de-atuacao-map\\\/valorizando-as-cadeias-da-sociobiodiversidade-do-xingu-pequi-um-sonho-possivel-15\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rem.sema.mt.gov.br\\\/areas-de-atuacao-map\\\/valorizando-as-cadeias-da-sociobiodiversidade-do-xingu-pequi-um-sonho-possivel-15\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/areas-de-atuacao-map\\\/valorizando-as-cadeias-da-sociobiodiversidade-do-xingu-pequi-um-sonho-possivel-15\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c1reas de atua\u00e7\u00e3o Maps\",\"item\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/en\\\/areas-de-atuacao-map\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Valorizando as Cadeias da Sociobiodiversidade do Xingu \u2013 \u201cPequi um Sonho Poss\u00edvel\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/#website\",\"url\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/\",\"name\":\"REM\",\"description\":\"Mato Grosso\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Valorizando as Cadeias da Sociobiodiversidade do Xingu \u2013 \u201cPequi um Sonho Poss\u00edvel\u201d - REM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rem.sema.mt.gov.br\/en\/areas-de-atuacao-map\/valorizando-as-cadeias-da-sociobiodiversidade-do-xingu-pequi-um-sonho-possivel-15\/","og_locale":"en_US","og_type":"article","og_title":"Valorizando as Cadeias da Sociobiodiversidade do Xingu \u2013 \u201cPequi um Sonho Poss\u00edvel\u201d - REM","og_url":"https:\/\/rem.sema.mt.gov.br\/en\/areas-de-atuacao-map\/valorizando-as-cadeias-da-sociobiodiversidade-do-xingu-pequi-um-sonho-possivel-15\/","og_site_name":"REM","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rem.sema.mt.gov.br\/areas-de-atuacao-map\/valorizando-as-cadeias-da-sociobiodiversidade-do-xingu-pequi-um-sonho-possivel-15\/","url":"https:\/\/rem.sema.mt.gov.br\/areas-de-atuacao-map\/valorizando-as-cadeias-da-sociobiodiversidade-do-xingu-pequi-um-sonho-possivel-15\/","name":"Valorizando as Cadeias da Sociobiodiversidade do Xingu \u2013 \u201cPequi um Sonho Poss\u00edvel\u201d - REM","isPartOf":{"@id":"https:\/\/rem.sema.mt.gov.br\/#website"},"datePublished":"2025-11-28T07:30:10+00:00","breadcrumb":{"@id":"https:\/\/rem.sema.mt.gov.br\/areas-de-atuacao-map\/valorizando-as-cadeias-da-sociobiodiversidade-do-xingu-pequi-um-sonho-possivel-15\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rem.sema.mt.gov.br\/areas-de-atuacao-map\/valorizando-as-cadeias-da-sociobiodiversidade-do-xingu-pequi-um-sonho-possivel-15\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rem.sema.mt.gov.br\/areas-de-atuacao-map\/valorizando-as-cadeias-da-sociobiodiversidade-do-xingu-pequi-um-sonho-possivel-15\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/rem.sema.mt.gov.br\/"},{"@type":"ListItem","position":2,"name":"\u00c1reas de atua\u00e7\u00e3o Maps","item":"https:\/\/rem.sema.mt.gov.br\/en\/areas-de-atuacao-map\/"},{"@type":"ListItem","position":3,"name":"Valorizando as Cadeias da Sociobiodiversidade do Xingu \u2013 \u201cPequi um Sonho Poss\u00edvel\u201d"}]},{"@type":"WebSite","@id":"https:\/\/rem.sema.mt.gov.br\/#website","url":"https:\/\/rem.sema.mt.gov.br\/","name":"REM","description":"Mato Grosso","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rem.sema.mt.gov.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/rem.sema.mt.gov.br\/en\/wp-json\/wp\/v2\/areas-de-atuacao-map\/124112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rem.sema.mt.gov.br\/en\/wp-json\/wp\/v2\/areas-de-atuacao-map"}],"about":[{"href":"https:\/\/rem.sema.mt.gov.br\/en\/wp-json\/wp\/v2\/types\/areas-de-atuacao-map"}],"wp:attachment":[{"href":"https:\/\/rem.sema.mt.gov.br\/en\/wp-json\/wp\/v2\/media?parent=124112"}],"wp:term":[{"taxonomy":"categoria-de-projetos-subprogram","embeddable":true,"href":"https:\/\/rem.sema.mt.gov.br\/en\/wp-json\/wp\/v2\/categoria-de-projetos-subprogram?post=124112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}