{"id":463,"date":"2022-11-21T14:57:27","date_gmt":"2022-11-21T17:57:27","guid":{"rendered":"https:\/\/devsweb.com.br\/rem_wp\/investimento-do-programa-rem-mt-incentiva-renda-e-protagonismo-indigena-na-cadeia-produtiva-do-babacu\/"},"modified":"2025-12-10T11:49:41","modified_gmt":"2025-12-10T14:49:41","slug":"investimento-do-programa-rem-mt-incentiva-renda-e-protagonismo-indigena-na-cadeia-produtiva-do-babacu","status":"publish","type":"post","link":"https:\/\/rem.sema.mt.gov.br\/en\/noticias\/investimento-do-programa-rem-mt-incentiva-renda-e-protagonismo-indigena-na-cadeia-produtiva-do-babacu\/","title":{"rendered":"Investimento do Programa REM MT incentiva renda e protagonismo ind\u00edgena na cadeia produtiva do baba\u00e7u"},"content":{"rendered":"<p><span style=\"font-size: 10pt;\">Cr\u00e9dito: Vit\u00f3ria Lopes\u00a0<\/span><\/p>\n<p><span style=\"font-size: 18pt;\"><span style=\"font-size: 36pt;\"><strong>E<\/strong><\/span>ntre as colinas de demorar a vista, na Terra 7 de Setembro, em Cacoal (RO), o povo ind\u00edgena Paiter Suru\u00ed conquista sua autonomia financeira, aliada com os saberes tradicionais, por meio da colheita do baba\u00e7u. Com 91 hectares de manejo, o baba\u00e7u rende para os ind\u00edgenas a extra\u00e7\u00e3o do \u00f3leo e da farinha, al\u00e9m de ser usado em seus artesanatos e na constru\u00e7\u00e3o de malocas (casas). Toda a cadeia de produ\u00e7\u00e3o envolve a participa\u00e7\u00e3o da etnia.<\/span><\/p>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">Antes de ser contemplada pelo edital do <a href=\"index.php\/pt\/atuacao-2\/afpct-2\">Subprograma de Agricultura Familiar e de Povos e Comunidades Tradicionais (AFPCTs)<\/a>, do Programa REM MT. os ind\u00edgenas faziam a extra\u00e7\u00e3o do \u00f3leo e farinha de baba\u00e7u de forma artesanal. Por\u00e9m, a vigil\u00e2ncia sanit\u00e1ria barrou a continuidade da produ\u00e7\u00e3o, conta Izanoel Irpererr\u00f3 Suru\u00ed.<br \/><img fetchpriority=\"high\" decoding=\"async\" src=\"images\/Izanoel_Irpererro_Surui.jpg\" alt=\"\" width=\"1032\" height=\"688\" \/><\/span><span style=\"font-size: 10pt;\"><b>Izanoel Irpererr\u00f3 Suru\u00ed, tesoureiro e benefici\u00e1rio do projeto Foto: Vit\u00f3ria Lopes \/ REM MT<\/b><\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">\u201cA gente estava fazendo artesanalmente, est\u00e1vamos vendendo a farinha e o \u00f3leo, e vendia para a comunidade pr\u00f3xima. S\u00f3 que a vigil\u00e2ncia viu a forma como est\u00e1vamos trabalhando, e aquilo \u00e9 aliment\u00edcio, temos que ter uma higiene e cuidado. Ent\u00e3o, a gente pensou em construir a agroind\u00fastria\u201d, conta Izanoel.<\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">Com o impedimento da venda, eles idealizaram o <a href=\"index.php\/pt\/atuacao-2\/afpct-2\/12-subprogramas\/267-afpct-projeto-babacu-toroya-paiter-surui\">Projeto Baba\u00e7u Toroya<\/a>. Por estar em um territ\u00f3rio ind\u00edgena, Izanoel, que hoje \u00e9 tesoureiro e benefici\u00e1rio do programa, explica que foi preciso criar uma associa\u00e7\u00e3o, para depois constituir a agroind\u00fastria.<\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">\u201cA gente projetou uma agroind\u00fastria, pensando em criar gera\u00e7\u00e3o de renda. Aquilo tamb\u00e9m trouxe pra gente como fazer uma agroind\u00fastria dentro de uma reserva ind\u00edgena? Vai ter muitas cr\u00edticas\u2019\u201d, revela.<\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-size: 18pt;\"><b>Apoio<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">Com incentivo do Programa REM MT, os ind\u00edgenas da Terra 7 de Setembro tiveram treinamento e capacita\u00e7\u00e3o, assim como apoio no marketing e na venda dos produtos. Foram investidos R$ 1.349.5600,00.<\/span><\/p>\n<p><span style=\"font-weight: 400; font-size: 18pt;\"><img decoding=\"async\" src=\"images\/Barracao_e_agroindustria_dos_Paiter_Surui_.jpg\" alt=\"\" width=\"1014\" height=\"676\" \/><\/span><span style=\"font-size: 10pt;\"><b>Barrac\u00e3o e agroind\u00fastria dos Paiter Suru\u00ed Foto: Vit\u00f3ria Lopes \/ REM MT<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">Agora, eles est\u00e3o finalizando a constru\u00e7\u00e3o de um barrac\u00e3o e ind\u00fastria, que logo entrar\u00e1 em opera\u00e7\u00e3o. O barrac\u00e3o foi constru\u00eddo em uma \u00e1rea afastada da comunidade, pr\u00f3ximo do baba\u00e7ual, em contato direto com a Amaz\u00f4nia.<\/span><\/p>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">Por ora, a ind\u00fastria est\u00e1 impossibilitada de funcionar pela falta de acesso a energia trif\u00e1sica. Os ind\u00edgenas buscaram pol\u00edticos e at\u00e9 mesmo parceiros para tentar trazer a rede de energia na aldeia, mas ainda n\u00e3o tiveram sucesso.\u00a0<\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">\u201cO desafio nos trouxe conhecimento\u201d, disse o coordenador do projeto Isaque Mopilo\u2019ava Suru\u00ed. As no\u00e7\u00f5es de venda e marketing dos produtos originados do baba\u00e7u eram desconhecidas pela comunidade. Mas eles j\u00e1 finalizaram os planejamentos de neg\u00f3cio e marketing.\u00a0<\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-size: 10pt;\"><b><img decoding=\"async\" src=\"images\/Isaque_Mopiloava_Surui.jpg\" alt=\"\" width=\"1071\" height=\"714\" \/><\/b><\/span><span style=\"font-size: 10pt;\"><b>Isaque Mopilo\u2019ava Suru\u00ed, coordenador do projeto Foto: Vit\u00f3ria Lopes \/ REM MT<\/b><\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">\u201cA estrat\u00e9gia que iniciamos dentro do processo foi de georreferenciamento, que \u00e9 o trabalho no campo, e tamb\u00e9m a unidade onde que vai ficar a agroind\u00fastria, com licenciamento pr\u00e9vio, instala\u00e7\u00e3o operacional e tamb\u00e9m o plano de neg\u00f3cios, o plano de gest\u00e3o e o marketing\u201d, concluiu Isaque.<\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-size: 18pt;\"><b>Protagonismo ind\u00edgena<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">Paiter significa \u201cgente de verdade, n\u00f3s mesmos\u201d. Portanto, sonham juntos em conquistar o protagonismo ind\u00edgena na cadeia produtiva do baba\u00e7u, pois desde a gest\u00e3o at\u00e9 a colheita da am\u00eandoa do baba\u00e7u, todos os envolvidos no projeto s\u00e3o da etnia Paiter Suru\u00ed.<\/span><\/p>\n<p><span style=\"font-weight: 400; font-size: 18pt;\"><img loading=\"lazy\" decoding=\"async\" src=\"images\/Indigena_Paiter_Surui_.jpg\" alt=\"\" width=\"1067\" height=\"711\" \/><\/span><span style=\"font-size: 10pt;\"><b>\u00cdndigena Paiter Suru\u00ed quebrando o baba\u00e7u e extraindo a castanha e o gongo, que fazem parte da alimenta\u00e7\u00e3o Foto: Vit\u00f3ria Lopes \/ REM MT<\/b><\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">\u201cAqui j\u00e1 temos uma pessoa formada em Direito e Administra\u00e7\u00e3o, t\u00e9cnico em Enfermagem, e minha irm\u00e3 fazendo Contabilidade. Ent\u00e3o, qual o nosso objetivo? Trazer esse profissional, fazer do seu territ\u00f3rio tamb\u00e9m a agroind\u00fastria. E dentro desse projeto de agroind\u00fastria, tem plano de gest\u00e3o, de marketing, ent\u00e3o a gente tem que entender tudo. Imagina agregar esse pessoal, que vai fazer a gest\u00e3o da agroind\u00fastria do seu territ\u00f3rio e fazer o protagonismo Paiter. Isso \u00e9 o nosso sonho, esse \u00e9 o nosso objetivo\u201d, conta Isaque Mopilo\u2019ava.<\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">Por almejar protagonismo total, eles acabaram emperrando em alguns pontos do projeto, especialmente nos processos burocr\u00e1ticos. Apesar das dificuldades, o engenheiro agr\u00f4nomo e coordenador das AFPCTs, Marcos Balbino, visualiza que a associa\u00e7\u00e3o tem muita vontade pr\u00f3pria de fazer acontecer a agroind\u00fastria.<\/span><\/p>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">A falta de uma rede de energia capaz de rodar a agroind\u00fastria tamb\u00e9m dificultou a inaugura\u00e7\u00e3o. A aldeia precisa de for\u00e7a pol\u00edtica para dar continuidade no projeto.\u00a0<\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">&#8220;A agroind\u00fastria \u00e9 o ponto chave do projeto deles e j\u00e1 est\u00e1 levantada. Est\u00e1 faltando algumas coisas de acabamento, mas os equipamentos j\u00e1 est\u00e3o comprados, est\u00e3o no fornecedor para n\u00e3o danificar, enquanto terminam a agroind\u00fastria. Eles t\u00eam um problema com a energia el\u00e9trica, que \u00e9 um problema que depende da a\u00e7\u00e3o p\u00fablica local, prefeitura e parceiros&#8221;, pontua Marcos.<\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">O coordenador refor\u00e7a, por\u00e9m, que o plano de neg\u00f3cios dos Paiter Suru\u00ed j\u00e1 est\u00e1 constru\u00eddo. &#8220;Eles querem ter j\u00e1 no\u00e7\u00e3o do mercado onde eles v\u00e3o vender cada tipo de produto. Pelo o que a gente conversou, eles pretendem atender tanto o varejo, quanto atacado. Ent\u00e3o, todos esses produtos v\u00e3o carregar a marca do povo Suru\u00ed&#8221;.\u00a0<\/span><\/p>\n<p><span style=\"font-size: 18pt;\"><b>Manter a floresta em p\u00e9<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">A conviv\u00eancia dos Paiter Suru\u00ed com a natureza \u00e9 t\u00e3o harm\u00f4nica, que araras e papagaios sentem-se \u00e0 vontade em voar entre eles. Cuidar do manejo do baba\u00e7ual com o bioma da Amaz\u00f4nia n\u00e3o s\u00f3 diz respeito em manter a floresta em p\u00e9, mas tamb\u00e9m em respeitar a sua cultura.<\/span><\/p>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">\u201cEssa agroind\u00fastria foi a forma do nosso entendimento do cuidado com a floresta, n\u00e3o pensando em desmatar, mas para o bem da comunidade, em como criar uma gera\u00e7\u00e3o de renda para o bem da floresta\u201d, comenta Izanoel.<\/span><\/p>\n<p><span style=\"font-size: 18pt;\"><b>Benef\u00edcios do \u00f3leo de baba\u00e7u<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">Principal fonte de renda dos Paiter Suru\u00ed, o baba\u00e7u tamb\u00e9m garante a seguran\u00e7a alimentar dos ind\u00edgenas. O \u00f3leo tem in\u00fameros benef\u00edcios, atuando na hidrata\u00e7\u00e3o da pele e cabelo, como tamb\u00e9m tem a\u00e7\u00e3o anti-inflamat\u00f3ria e cicatrizante. Pode ser usado em hospitais e escolas.<\/span><\/p>\n<p><span style=\"font-weight: 400; font-size: 18pt;\"><img loading=\"lazy\" decoding=\"async\" src=\"images\/Castanha_de_babacu.jpg\" alt=\"\" width=\"1041\" height=\"694\" \/><\/span><span style=\"font-size: 10pt;\"><b>Castanha de baba\u00e7u Foto: Vit\u00f3ria Lopes \/ REM MT<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">Com a farinha, \u00e9 feito o tradicional beiju, bolacha e mingau. E n\u00e3o s\u00f3 o fruto serve para os ind\u00edgenas, pois eles tamb\u00e9m utilizam da folha do baba\u00e7u para tran\u00e7ar cestos e cobrir malocas.\u00a0<\/span><\/p>\n<p><span style=\"font-size: 18pt;\"><b>Programa REDD Early Movers &#8211; REM<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">Em 2012, o governo alem\u00e3o atrav\u00e9s do Minist\u00e9rio Federal da Coopera\u00e7\u00e3o Econ\u00f4mica e Desenvolvimento (BMZ) estabeleceu o Programa Global REDD Early Movers (REM) &#8211; Pioneiros em Redu\u00e7\u00e3o de Emiss\u00f5es por Desmatamento e Degrada\u00e7\u00e3o Florestal (REDD), em portugu\u00eas. Este programa prev\u00ea o apoio a pa\u00edses e estados que implementaram iniciativas pioneiras em conserva\u00e7\u00e3o de florestas e redu\u00e7\u00e3o das emiss\u00f5es por desmatamento e degrada\u00e7\u00e3o.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400; font-size: 18pt;\">Lan\u00e7ado na Confer\u00eancia Rio+20 em junho de 2012, o Programa REDD Early Movers (REM) \u00e9 uma iniciativa inovadora que recompensa os pioneiros na conserva\u00e7\u00e3o florestal e na mitiga\u00e7\u00e3o das mudan\u00e7as clim\u00e1ticas. O Programa fornece pagamentos baseados em resultados para redu\u00e7\u00e3o de emiss\u00f5es por desmatamento verificadas, tornando-se assim uma iniciativa de REDD, de acordo com as decis\u00f5es assumidas na Conven\u00e7\u00e3o-Quadro das Na\u00e7\u00f5es Unidas sobre Mudan\u00e7a do Clima (UNFCCC).<\/span><\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Vit\u00f3ria Lopes\u00a0 Entre as colinas de demorar a vista, na Terra 7 de Setembro, em Cacoal (RO), o povo ind\u00edgena Paiter Suru\u00ed conquista sua autonomia financeira, aliada com os saberes tradicionais, por meio da colheita do baba\u00e7u. Com 91 hectares de manejo, o baba\u00e7u rende para os ind\u00edgenas a extra\u00e7\u00e3o do \u00f3leo e da [&hellip;]<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","ocean_front_end_style_editor":"no","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[19],"tags":[],"class_list":["post-463","post","type-post","status-publish","format-standard","hentry","category-noticias","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Investimento do Programa REM MT incentiva renda e protagonismo ind\u00edgena na cadeia produtiva do baba\u00e7u - REM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rem.sema.mt.gov.br\/en\/noticias\/investimento-do-programa-rem-mt-incentiva-renda-e-protagonismo-indigena-na-cadeia-produtiva-do-babacu\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investimento do Programa REM MT incentiva renda e protagonismo ind\u00edgena na cadeia produtiva do baba\u00e7u - REM\" \/>\n<meta property=\"og:description\" content=\"Cr\u00e9dito: Vit\u00f3ria Lopes\u00a0 Entre as colinas de demorar a vista, na Terra 7 de Setembro, em Cacoal (RO), o povo ind\u00edgena Paiter Suru\u00ed conquista sua autonomia financeira, aliada com os saberes tradicionais, por meio da colheita do baba\u00e7u. Com 91 hectares de manejo, o baba\u00e7u rende para os ind\u00edgenas a extra\u00e7\u00e3o do \u00f3leo e da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rem.sema.mt.gov.br\/en\/noticias\/investimento-do-programa-rem-mt-incentiva-renda-e-protagonismo-indigena-na-cadeia-produtiva-do-babacu\/\" \/>\n<meta property=\"og:site_name\" content=\"REM\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-21T17:57:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-10T14:49:41+00:00\" \/>\n<meta name=\"author\" content=\"REM MT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"REM MT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/noticias\\\/investimento-do-programa-rem-mt-incentiva-renda-e-protagonismo-indigena-na-cadeia-produtiva-do-babacu\\\/\",\"url\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/noticias\\\/investimento-do-programa-rem-mt-incentiva-renda-e-protagonismo-indigena-na-cadeia-produtiva-do-babacu\\\/\",\"name\":\"Investimento do Programa REM MT incentiva renda e protagonismo ind\u00edgena na cadeia produtiva do baba\u00e7u - REM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/#website\"},\"datePublished\":\"2022-11-21T17:57:27+00:00\",\"dateModified\":\"2025-12-10T14:49:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/#\\\/schema\\\/person\\\/d7f162d30bdd095e4a02c2e5f5d4b221\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/noticias\\\/investimento-do-programa-rem-mt-incentiva-renda-e-protagonismo-indigena-na-cadeia-produtiva-do-babacu\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rem.sema.mt.gov.br\\\/noticias\\\/investimento-do-programa-rem-mt-incentiva-renda-e-protagonismo-indigena-na-cadeia-produtiva-do-babacu\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/noticias\\\/investimento-do-programa-rem-mt-incentiva-renda-e-protagonismo-indigena-na-cadeia-produtiva-do-babacu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investimento do Programa REM MT incentiva renda e protagonismo ind\u00edgena na cadeia produtiva do baba\u00e7u\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/#website\",\"url\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/\",\"name\":\"REM\",\"description\":\"Mato Grosso\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rem.sema.mt.gov.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Investimento do Programa REM MT incentiva renda e protagonismo ind\u00edgena na cadeia produtiva do baba\u00e7u - REM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rem.sema.mt.gov.br\/en\/noticias\/investimento-do-programa-rem-mt-incentiva-renda-e-protagonismo-indigena-na-cadeia-produtiva-do-babacu\/","og_locale":"en_US","og_type":"article","og_title":"Investimento do Programa REM MT incentiva renda e protagonismo ind\u00edgena na cadeia produtiva do baba\u00e7u - REM","og_description":"Cr\u00e9dito: Vit\u00f3ria Lopes\u00a0 Entre as colinas de demorar a vista, na Terra 7 de Setembro, em Cacoal (RO), o povo ind\u00edgena Paiter Suru\u00ed conquista sua autonomia financeira, aliada com os saberes tradicionais, por meio da colheita do baba\u00e7u. Com 91 hectares de manejo, o baba\u00e7u rende para os ind\u00edgenas a extra\u00e7\u00e3o do \u00f3leo e da [&hellip;]","og_url":"https:\/\/rem.sema.mt.gov.br\/en\/noticias\/investimento-do-programa-rem-mt-incentiva-renda-e-protagonismo-indigena-na-cadeia-produtiva-do-babacu\/","og_site_name":"REM","article_published_time":"2022-11-21T17:57:27+00:00","article_modified_time":"2025-12-10T14:49:41+00:00","author":"REM MT","twitter_card":"summary_large_image","twitter_misc":{"Written by":"REM MT","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rem.sema.mt.gov.br\/noticias\/investimento-do-programa-rem-mt-incentiva-renda-e-protagonismo-indigena-na-cadeia-produtiva-do-babacu\/","url":"https:\/\/rem.sema.mt.gov.br\/noticias\/investimento-do-programa-rem-mt-incentiva-renda-e-protagonismo-indigena-na-cadeia-produtiva-do-babacu\/","name":"Investimento do Programa REM MT incentiva renda e protagonismo ind\u00edgena na cadeia produtiva do baba\u00e7u - REM","isPartOf":{"@id":"https:\/\/rem.sema.mt.gov.br\/#website"},"datePublished":"2022-11-21T17:57:27+00:00","dateModified":"2025-12-10T14:49:41+00:00","author":{"@id":"https:\/\/rem.sema.mt.gov.br\/#\/schema\/person\/d7f162d30bdd095e4a02c2e5f5d4b221"},"breadcrumb":{"@id":"https:\/\/rem.sema.mt.gov.br\/noticias\/investimento-do-programa-rem-mt-incentiva-renda-e-protagonismo-indigena-na-cadeia-produtiva-do-babacu\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rem.sema.mt.gov.br\/noticias\/investimento-do-programa-rem-mt-incentiva-renda-e-protagonismo-indigena-na-cadeia-produtiva-do-babacu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rem.sema.mt.gov.br\/noticias\/investimento-do-programa-rem-mt-incentiva-renda-e-protagonismo-indigena-na-cadeia-produtiva-do-babacu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/rem.sema.mt.gov.br\/"},{"@type":"ListItem","position":2,"name":"Investimento do Programa REM MT incentiva renda e protagonismo ind\u00edgena na cadeia produtiva do baba\u00e7u"}]},{"@type":"WebSite","@id":"https:\/\/rem.sema.mt.gov.br\/#website","url":"https:\/\/rem.sema.mt.gov.br\/","name":"REM","description":"Mato Grosso","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rem.sema.mt.gov.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/rem.sema.mt.gov.br\/en\/wp-json\/wp\/v2\/posts\/463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rem.sema.mt.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rem.sema.mt.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rem.sema.mt.gov.br\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/rem.sema.mt.gov.br\/en\/wp-json\/wp\/v2\/comments?post=463"}],"version-history":[{"count":1,"href":"https:\/\/rem.sema.mt.gov.br\/en\/wp-json\/wp\/v2\/posts\/463\/revisions"}],"predecessor-version":[{"id":4662,"href":"https:\/\/rem.sema.mt.gov.br\/en\/wp-json\/wp\/v2\/posts\/463\/revisions\/4662"}],"wp:attachment":[{"href":"https:\/\/rem.sema.mt.gov.br\/en\/wp-json\/wp\/v2\/media?parent=463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rem.sema.mt.gov.br\/en\/wp-json\/wp\/v2\/categories?post=463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rem.sema.mt.gov.br\/en\/wp-json\/wp\/v2\/tags?post=463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}